{"id":427,"date":"2023-02-18T12:54:40","date_gmt":"2023-02-18T12:54:40","guid":{"rendered":"https:\/\/run-and-roll.com\/?p=427"},"modified":"2023-11-07T15:46:19","modified_gmt":"2023-11-07T15:46:19","slug":"where-to-run-in-grenoble","status":"publish","type":"post","link":"https:\/\/run-and-roll.com\/fr\/where-to-run-in-grenoble\/","title":{"rendered":"<strong>O\u00f9 courir \u00e0 Grenoble ? Je coure \u00e0 la maison !<\/strong>"},"content":{"rendered":"<p class=\"has-text-align-justify\">Un article un peu sp\u00e9cial aujourd'hui, parce que Grenoble est ma ville natale (enfin presque). Je vais donc essayer de rester objective. Pour \u00eatre honn\u00eate la ville en elle-m\u00eame n'est pas ma pr\u00e9f\u00e9r\u00e9e pour courir... Mais clairement ma pr\u00e9f\u00e9r\u00e9e en France pour y vivre, notamment en tant qu'\u00e9tudiant.e (ok, c'est bon je ne suis plus objective \u00e0 partir d'ici). Comme d'habitude, voici donc une petite s\u00e9lection de mes running spots pr\u00e9f\u00e9r\u00e9s \u00e0 Gregre (pour les intimes).<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Profil de la ville<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">G\u00e9ographie : Capitale des Alpes, on fait souvent r\u00e9f\u00e9rence \u00e0 Grenoble comme une \"cuvette\" car elle est encercl\u00e9e par les massifs du Vercors, de la Chartreuse et de Belledone. Fun fact en revanche, Grenoble est en r\u00e9alit\u00e9 la ville la plus plate de France.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Population : 160 000 pour la ville en elle-m\u00eame, 450 000 pour toute l'agglom\u00e9ration.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Climat : Continental : (tr\u00e8s) froid en hiver (m\u00eame s'il y a de moins en moins de neige chaque ann\u00e9e), (super) chaud en \u00e9t\u00e9. &nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Grenoble est connue pour : Les montagnes \u00e9videmment, le ski, la rando et le trail \u00e9tant des attractions touristiques majeures. Dans la ville en elle-m\u00eame, le fort de la Bastille et son t\u00e9l\u00e9ph\u00e9rique. Grenoble est aussi connue pour sa vie \u00e9tudiante (mais c'est mort en \u00e9t\u00e9).<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Adapt\u00e9e \u00e0 la course \u00e0 pied : \u2734\ufe0f\u2734\ufe0f\u2734\ufe0f<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comment j'ai atterri \u00e0 Grenoble<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify\">J'ai commenc\u00e9 mes \u00e9tudes sup\u00e9rieures \u00e0 Grenoble, o\u00f9 je suis rest\u00e9e deux ans pour ma classe pr\u00e9pa. C'est \u00e0 ce moment l\u00e0 que j'ai commenc\u00e9 la course \u00e0 pied (juste quelques kilom\u00e8tres par semaine \u00e0 cette \u00e9poque), gr\u00e2ce \u00e0 (\u00e0 cause ?) de mon copain de l'\u00e9poque. Je suis revenue \u00e0 Grenoble deux ans plus tard, apr\u00e8s <a href=\"https:\/\/run-and-roll.com\/fr\/where-to-run-in-berlin\/\" target=\"_blank\" rel=\"noreferrer noopener\">Berlin<\/a>. Comme j'en avait marre du management, du marketing et autre ***nneries enseign\u00e9es en \u00e9cole de commerce, j'ai pris une ann\u00e9e de c\u00e9sure pour terminer mon master 2 en \u00e9conomie du d\u00e9veloppement \u00e0 l'universit\u00e9 de Grenoble (on perd pas de temps).<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Premi\u00e8re sortie<\/h3>\n\n\n\n<p class=\"has-text-align-justify\">Si je me souviens bien, ma toute premi\u00e8re sortie course \u00e0 pied remonte \u00e0 ma deuxi\u00e8me ann\u00e9e de pr\u00e9pa chez mes parents (\u00e0 25 km de Grenoble). A l'\u00e9poque, j'\u00e9tais \u00e9puis\u00e9e et essouffl\u00e9e apr\u00e8s 2km, et ma seule motivation \u00e9tait d'essayer de suivre mon copain. Nous avons pris l'habitude de nous retrouver une fois par semaine \u00e0 Grenoble apr\u00e8s les cours pour une petite sortie dans le parc Paul Mistral, et \u00e0 partir de l\u00e0, j'ai commenc\u00e9 \u00e0 courir seule le week-end chez mes parents. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Je ne me souviens pas exactement de ma \"deuxi\u00e8me premi\u00e8re\" sortie quand je suis revenue \u00e0 Grenoble deux ans plus tard. Je me suis install\u00e9e en septembre en pleine pr\u00e9paration du 10 kilom\u00e8tres du Run in Lyon qui a lieu d\u00e9but octobre, donc j'imagine qu'une de mes premi\u00e8res sorties a \u00e9t\u00e9 une s\u00e9ance de fractionn\u00e9 \u00e0 Paul Mistral.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">La plupart de mes sorties \u00e0 Grenoble \u00e9taient courtes, vu que je retournais chez mes parents \u00e0 la campagne le weekend pour mes sorties longues du dimanche.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O\u00f9 courir \u00e0 Grenoble ? Mes endroits pr\u00e9f\u00e9r\u00e9s pour courir<\/strong><\/h3>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Le parc Paul Mistral (aka le PPM pour les intimes), le classique du centre ville<\/strong><\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\">Aaah le parc Paul Mistral... Une belle illustration de ce qu'est la vie \u00e0 Grenoble. Des \u00e9tudiants qui pic-niquent sur les pelouses, des jeunes qui s'entra\u00eenent \u00e0 la slackline entre deux arbres, des joggeurs, des p\u00e9tanqueurs, des supporters les soirs de match, des dealers... Une petite touche de Berlin en quelque sorte. Une des premi\u00e8res choses que vous apprendrez en arrivant \u00e0 Grenoble : ne traversez pas le PPM la nuit !<\/p>\n\n\n\n<p class=\"\">Pourquoi courir l\u00e0-bas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Le parc est central et facilement d'o\u00f9 que vous veniez. Pratique pour des sorties apr\u00e8s le travail\/les cours et pour retrouver d'autres coureurs.<\/li>\n\n\n\n<li class=\"\">C'est plat, et c'est des chemins en terre<\/li>\n\n\n\n<li class=\"\">Parfait pour le fractionn\u00e9<\/li>\n\n\n\n<li class=\"\">Il y a un genre de piste d'athl\u00e9tisme (\"l'anneau de vitesse\"). C'est pas du tartan mais \u00e7a peut \u00eatre pratique pour le travail de vitesse.<\/li>\n\n\n\n<li class=\"\">Il y a plusieurs fontaines d'eau potable dans le parc<\/li>\n<\/ul>\n\n\n\n<p class=\"\">... et pourquoi pas<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">En termes de s\u00e9curit\u00e9, c'est une no go zone d\u00e8s que la nuit tombe<\/li>\n\n\n\n<li class=\"\">Il y a beaucoup de monde le soir et le weekend, soyez pr\u00eats \u00e0 slalomer entre les gens, m\u00eame si les all\u00e9es sont larges<\/li>\n\n\n\n<li class=\"\">Le parc n'est pas si grand que \u00e7a, pour les sorties longues mieux vaut continuer sur les berges de l'Is\u00e8re (qui sont toutes proches)<\/li>\n\n\n\n<li class=\"\">C'est un parc tr\u00e8s \"urbain\" : on a pas du tout l'impression d'\u00eatre dans la nature, on est pas coup\u00e9s de la circulation. Pour \u00e7a, pr\u00e9f\u00e9rez les berges de l'Is\u00e8re.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"174\" data-id=\"441\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=640%2C174&#038;ssl=1\" alt=\"\" class=\"wp-image-441\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=1024%2C279&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=300%2C82&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=768%2C210&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=1536%2C419&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=18%2C5&amp;ssl=1 18w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=850%2C232&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=24%2C7&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=36%2C10&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?resize=48%2C13&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?w=1807&amp;ssl=1 1807w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/fractionne-PPM.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Classic fractionn\u00e9 au PPM<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Les berges de l'Is\u00e8re, pour une sortie rafra\u00eechissante<\/strong><\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\">Si vous cherchez un itin\u00e9raire plus tranquille, loin des voitures, avec la sensation d'\u00eatre dans la nature (en \u00e9tant compl\u00e8tement dans la ville), les berges sont un bon choix. C'est m\u00eame mon endroit pr\u00e9f\u00e9r\u00e9 pour courir \u00e0 Grenoble.<\/p>\n\n\n\n<p class=\"\">Pourquoi courir l\u00e0-bas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Un parcours potentiellement tr\u00e8s long. Il y a une piste cyclable tout le long de l'Is\u00e8re, de Valence \u00e0 Grenoble, et de l'autre c\u00f4t\u00e9 de Grenoble \u00e0 Aix les Bains et plus loin (m\u00eame si \u00e0 certains moments la piste s'\u00e9loigne de la berge). Je courais entre le centre ville de Grenoble, Saint Martin d'H\u00e8res et la zone du campus.<\/li>\n\n\n\n<li class=\"\">La piste cyclable est un peu en surplomb de la rivi\u00e8re et peut \u00eatre un peu dangereuse (le matin et le soir, c'est une v\u00e9ritable autoroute pour cyclistes qui peuvent rouler tr\u00e8s vite). Je recommande de prendre le sentier \u00e9troit en dessous qui donne directement sur la berge. Vous aurez l'impression de courir dans la nature, et c'est beaucoup moins ennuyeux que de suivre la piste cyclable en goudron. Vous pourrez m\u00eame voir des gens faire de l'aviron sur la rivi\u00e8re. Du c\u00f4t\u00e9 de Grenoble, le sentier se termine au mus\u00e9e Notre Dame, o\u00f9 vous devrez reprendre la piste cyclable. Dans la direction de Saint Martin d'H\u00e8res, elle est si longue que je ne sais m\u00eame pas o\u00f9 elle s'arr\u00eate. Je n'ai jamais essay\u00e9 de courir de l'autre c\u00f4t\u00e9 de l'Is\u00e8re (c\u00f4t\u00e9 Bastille), mais c'est \u00e0 peu pr\u00e8s la m\u00eame chose, vous devez prendre la piste cyclable dans le centre ville, et ensuite vous trouverez un sentier une fois que vous approchez de Saint Martin d'H\u00e8res.<\/li>\n\n\n\n<li class=\"\">On la sensation de courir en nature ou de faire du trail urbain sans aucun d\u00e9nivel\u00e9<\/li>\n\n\n\n<li class=\"\">Pas besoin de trop r\u00e9fl\u00e9chir au parcours, il y a juste \u00e0 suivre le chemin<\/li>\n<\/ul>\n\n\n\n<p class=\"\">... et pourquoi pas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Ok, on s'ennuie un peu \u00e0 force de faire des allers-retours en quasi ligne droite. Pour varier un peu, on peut int\u00e9grer une portion sur les berges dans un tour plus grand ou compl\u00e9ter en allant courir au PPM.<\/li>\n\n\n\n<li class=\"\">\u00c7a m'est d\u00e9j\u00e0 arriv\u00e9e de courir plus loin que pr\u00e9vu sans m'en rendre compte. Soit on fait demi-tour par le m\u00eame chemin, soit on sort des berges et on essaie de comprendre dans quelle partie de la ville on s'est retrouv\u00e9...<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"215\" data-id=\"442\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=640%2C215&#038;ssl=1\" alt=\"\" class=\"wp-image-442\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=1024%2C344&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=300%2C101&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=768%2C258&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=18%2C6&amp;ssl=1 18w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=850%2C285&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=24%2C8&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=36%2C12&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?resize=48%2C16&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?w=1448&amp;ssl=1 1448w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-centre.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Vers le centre ville<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"185\" data-id=\"443\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=640%2C185&#038;ssl=1\" alt=\"\" class=\"wp-image-443\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=1024%2C296&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=300%2C87&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=768%2C222&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=18%2C5&amp;ssl=1 18w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=850%2C246&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=24%2C7&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=36%2C10&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?resize=48%2C14&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?w=1530&amp;ssl=1 1530w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/berges-isere-campus.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Vers le campus (et au del\u00e0)<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"\"><strong>Le fort de la Bastille, pour les braves !<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-445\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/BastilleGrenoble.jpg?resize=48%2C36&amp;ssl=1 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\">Le classique du trail urbain ! La Bastille (qui n'a rien \u00e0 voir avec la Bastille \u00e0 Paris) est une ancienne forteresse perch\u00e9e \u00e0 476m au pied de la Chartreuse et surplombant la ville. Elle est situ\u00e9e de l'autre c\u00f4t\u00e9 de la rivi\u00e8re, en face du centre ville. Elle est bien connue pour son t\u00e9l\u00e9ph\u00e9rique qui passe au-dessus de la rivi\u00e8re. Il y a deux options pour y monter. La premi\u00e8re (la plus habituelle) commence rue Saint Laurent, \u00e0 la fontaine du lion. L'autre commence dans le \"Jardin des dauphins\" sur le Quai de France, juste en face du grand pont. Selon le point de d\u00e9part, il y a entre 2 et 3 km \u00e0 monter, mais avec environ 250m de d\u00e9nivel\u00e9 ! Autrement dit, on ne fait que monter tout le long ! On peut \u00e9galement combiner les deux itin\u00e9raires pour faire une boucle en montant d'un c\u00f4t\u00e9 et en descendant de l'autre.<\/p>\n\n\n\n<p class=\"\">Pourquoi courir l\u00e0-bas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Pour la vue imprenable en haut !<\/li>\n\n\n\n<li class=\"\">C'est un bon entrainement en c\u00f4te pour le trail tout en restant en ville. En revanche, le parcours n'est pas technique, le chemin est en gravier.<\/li>\n\n\n\n<li class=\"\">Pas de voitures !<\/li>\n\n\n\n<li class=\"\">Pour une vraie longue sortie trail, on peut pousser jusqu'au Mont Jalla (635m), o\u00f9 m\u00eame monter jusqu'au Mont Rachais (un peu plus de 1000m). Les distances sont courtes, mais la pente est raide !<\/li>\n<\/ul>\n\n\n\n<p class=\"\">... et pourquoi pas<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Autant le dire tout de suite : c'est pas facile, il y a 250m de d\u00e9nivel\u00e9 \u00e0 se farcir en moins de 3km.<\/li>\n\n\n\n<li class=\"\">Ce n'est pas un parcours de trail tr\u00e8s vari\u00e9, juste une mont\u00e9e descente.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"446\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-446\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?resize=48%2C36&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/080-Grenoble-Fort-de-la-Bastille.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Alors \u00e7a vaut le coup non ?<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"\"><strong>La zone du campus, pour un peu de calme (en th\u00e9orie)<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-447\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/campus.jpg?resize=48%2C36&amp;ssl=1 48w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\">Pour les \u00e9tudiants parmi vous. Le campus est situ\u00e9 \u00e0 Saint Martin d'H\u00e8res, et donne sur les berges de l'Is\u00e8re.<\/p>\n\n\n\n<p class=\"\">Pourquoi courir l\u00e0-bas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">Beaucoup moins de circulation qu'ailleurs dans Grenoble<\/li>\n\n\n\n<li class=\"\">Pratique si vous logez pas loin de l'universit\u00e9<\/li>\n\n\n\n<li class=\"\">Possible de combiner avec un portion sur les berges de l'Is\u00e8re<\/li>\n\n\n\n<li class=\"\">On peut s'arr\u00eater au parc de street workout sur le campus<\/li>\n\n\n\n<li class=\"\">C'est plat<\/li>\n\n\n\n<li class=\"\">Possible de faire une sortie assez longue (sans s'ennuyer)<\/li>\n<\/ul>\n\n\n\n<p class=\"\">... et pourquoi pas :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\">A moins d'aller sur le chemin le long des berges, on court sur route goudronn\u00e9e tout le long<\/li>\n\n\n\n<li class=\"\">M\u00eame sans voiture, il y a quand m\u00eame pas mal de trafic : cyclistes, bus, pi\u00e9tons<\/li>\n\n\n\n<li class=\"\">Le campus \u00e9tant assez vaste, on peut vite se perdre...<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"202\" data-id=\"444\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=640%2C202&#038;ssl=1\" alt=\"\" class=\"wp-image-444\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=1024%2C323&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=300%2C95&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=768%2C242&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=18%2C6&amp;ssl=1 18w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=850%2C268&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=24%2C8&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=36%2C11&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?resize=48%2C15&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?w=1495&amp;ssl=1 1495w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/Combo.png?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Combo berges de l'Is\u00e8re, centre-ville et campus<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"\"><strong>La montagne, \u00e7a vous gagne<\/strong><\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\">L'avantage de vivre \u00e0 Grenoble, c'est que la montagne n'est jamais tr\u00e8s loin, avec une infinit\u00e9 de parcours pour le trail. Chartreuse, Vercors, Belledone, Oisan, Taillefer\u2026 Il existe plusieurs \"stations de trail\" officielles autour de Grenoble (<a href=\"https:\/\/www.chartreuse-tourisme.com\/a-voir-a-faire\/marcher-courir-rouler\/trail\/station-de-trail-et-accueils\/\" target=\"_blank\" rel=\"noreferrer noopener\">Chartreuse<\/a>, <a href=\"https:\/\/www.onpiste.com\/explorer\/destinations\/vercors-villard-de-lans-30\" target=\"_blank\" rel=\"noreferrer noopener\">Vercors<\/a> et <a href=\"https:\/\/www.onpiste.com\/explorer\/destinations\/oisans-46\" target=\"_blank\" rel=\"noreferrer noopener\">Oisan<\/a>), la plupart accessibles par transports en commun, qui proposent diff\u00e9rents parcours de trial bien balis\u00e9s et pour tous les niveaux. D'autres stations de ski comme Chamrousse en proposent \u00e9galement. Sinon, il suffit de choisir un parcours de randonn\u00e9e et de l'utiliser comme parcours de trail. Attention cependant, certains peuvent \u00eatre tr\u00e8s techniques (avec des parties \"escalade\", des \u00e9chelles, des passages \u00e9troits sur des cr\u00eates, etc). Si vous \u00eates perdu dans ce vaste choix, dirigez vous vers l'office de tourisme, demandez aux traileurs ou aux groupes de randonneurs locaux. L'universit\u00e9 a aussi son propre groupe de trail qui organise des sorties autour de Grenoble.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"450\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-450\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?resize=48%2C36&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134518-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Plateau de lacs<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"451\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-451\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?resize=48%2C36&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20170825_134523-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Plateau de lacs<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"448\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-448\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?resize=48%2C36&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200913_104949-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Au dessus de Saint Pierre de Chartreuse<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"482\" data-id=\"453\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843.jpg?resize=640%2C482&#038;ssl=1\" alt=\"\" class=\"wp-image-453\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843-scaled.jpg?resize=1024%2C771&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843-scaled.jpg?resize=300%2C226&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843-scaled.jpg?resize=768%2C578&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843-scaled.jpg?resize=1536%2C1157&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20220812_095843-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">La grande Sure<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"449\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-449\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?resize=48%2C36&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_105558-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Le pas de la cl\u00e9 et le bec de l\u2019Orient<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"452\" src=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" class=\"wp-image-452\" srcset=\"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=16%2C12&amp;ssl=1 16w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=850%2C638&amp;ssl=1 850w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=24%2C18&amp;ssl=1 24w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=36%2C27&amp;ssl=1 36w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?resize=48%2C36&amp;ssl=1 48w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/IMG_20200810_122038-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\">Le pas de la cl\u00e9 et le bec de l\u2019Orient<\/figcaption><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\">De haut en bas : Taillefer, Chartreuse et Vercors<\/figcaption><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\"><strong>Et vous, quels sont vos parcours pr\u00e9f\u00e9r\u00e9s \u00e0 Grenoble et autour ?<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Un article un peu sp\u00e9cial aujourd'hui, parce que Grenoble est ma ville natale (enfin presque). Je vais donc essayer de rester objective. Pour \u00eatre honn\u00eate la ville en elle-m\u00eame n'est pas ma pr\u00e9f\u00e9r\u00e9e pour courir... Mais clairement ma pr\u00e9f\u00e9r\u00e9e en France pour y vivre<\/p>","protected":false},"author":1,"featured_media":439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[6,7,54,56,24,25,55,29],"class_list":["post-427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europe","tag-running","tag-sports","tag-france","tag-grenoble","tag-running-2","tag-running-routes","tag-sports-2","tag-travel-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Where to run in Grenoble?\u00a0 Running back home! - Run n&#039; Roll<\/title>\n<meta name=\"description\" content=\"Doing an exchange semester in the capital of the Alps? Pack your road and your trail running shoes, I&#039;m taking you!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/run-and-roll.com\/fr\/where-to-run-in-grenoble\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Where to run in Grenoble?\u00a0 Running back home! - Run n&#039; Roll\" \/>\n<meta property=\"og:description\" content=\"Doing an exchange semester in the capital of the Alps? Pack your road and your trail running shoes, I&#039;m taking you!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/run-and-roll.com\/fr\/where-to-run-in-grenoble\/\" \/>\n<meta property=\"og:site_name\" content=\"Run n&#039; Roll\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-18T12:54:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T15:46:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Running Mzungu\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/\"},\"author\":{\"name\":\"Running Mzungu\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#\\\/schema\\\/person\\\/817a2ddf7491e0acff8886f2dc54a32e\"},\"headline\":\"Where to run in Grenoble?\u00a0 Running back home!\",\"datePublished\":\"2023-02-18T12:54:40+00:00\",\"dateModified\":\"2023-11-07T15:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/\"},\"wordCount\":1685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/run-and-roll.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/feature-photo.jpg?fit=1920%2C1280&ssl=1\",\"keywords\":[\"#running\",\"#sports\",\"france\",\"grenoble\",\"running\",\"running routes\",\"sports\",\"travel\"],\"articleSection\":[\"Europe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/\",\"url\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/\",\"name\":\"Where to run in Grenoble?\u00a0 Running back home! - Run n&#039; Roll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/run-and-roll.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/feature-photo.jpg?fit=1920%2C1280&ssl=1\",\"datePublished\":\"2023-02-18T12:54:40+00:00\",\"dateModified\":\"2023-11-07T15:46:19+00:00\",\"description\":\"Doing an exchange semester in the capital of the Alps? Pack your road and your trail running shoes, I'm taking you!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/run-and-roll.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/feature-photo.jpg?fit=1920%2C1280&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/run-and-roll.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/feature-photo.jpg?fit=1920%2C1280&ssl=1\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/where-to-run-in-grenoble\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/run-and-roll.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Where to run in Grenoble?\u00a0 Running back home!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#website\",\"url\":\"https:\\\/\\\/run-and-roll.com\\\/\",\"name\":\"Run n&#039; Roll\",\"description\":\"The running guide for travelers and expats\",\"publisher\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/run-and-roll.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#organization\",\"name\":\"Run n&#039; Roll\",\"url\":\"https:\\\/\\\/run-and-roll.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/run-and-roll.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-cropped-cropped-cropped-cropped-RUN-N-roll-v6-2-1.png?fit=1500%2C844&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/run-and-roll.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-cropped-cropped-cropped-cropped-RUN-N-roll-v6-2-1.png?fit=1500%2C844&ssl=1\",\"width\":1500,\"height\":844,\"caption\":\"Run n&#039; Roll\"},\"image\":{\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/run-and-roll.com\\\/#\\\/schema\\\/person\\\/817a2ddf7491e0acff8886f2dc54a32e\",\"name\":\"Running Mzungu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e41d98daf143a11ea956e9d65b9193f35dbe529bb31c5f98847d0b4cf98d551?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e41d98daf143a11ea956e9d65b9193f35dbe529bb31c5f98847d0b4cf98d551?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9e41d98daf143a11ea956e9d65b9193f35dbe529bb31c5f98847d0b4cf98d551?s=96&d=mm&r=g\",\"caption\":\"Running Mzungu\"},\"url\":\"https:\\\/\\\/run-and-roll.com\\\/fr\\\/author\\\/lisa-reboud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Where to run in Grenoble?\u00a0 Running back home! - Run n&#039; Roll","description":"Doing an exchange semester in the capital of the Alps? Pack your road and your trail running shoes, I'm taking you!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/run-and-roll.com\/fr\/where-to-run-in-grenoble\/","og_locale":"fr_FR","og_type":"article","og_title":"Where to run in Grenoble?\u00a0 Running back home! - Run n&#039; Roll","og_description":"Doing an exchange semester in the capital of the Alps? Pack your road and your trail running shoes, I'm taking you!","og_url":"https:\/\/run-and-roll.com\/fr\/where-to-run-in-grenoble\/","og_site_name":"Run n&#039; Roll","article_published_time":"2023-02-18T12:54:40+00:00","article_modified_time":"2023-11-07T15:46:19+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg","type":"image\/jpeg"}],"author":"Running Mzungu","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#article","isPartOf":{"@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/"},"author":{"name":"Running Mzungu","@id":"https:\/\/run-and-roll.com\/#\/schema\/person\/817a2ddf7491e0acff8886f2dc54a32e"},"headline":"Where to run in Grenoble?\u00a0 Running back home!","datePublished":"2023-02-18T12:54:40+00:00","dateModified":"2023-11-07T15:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/"},"wordCount":1685,"commentCount":0,"publisher":{"@id":"https:\/\/run-and-roll.com\/#organization"},"image":{"@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg?fit=1920%2C1280&ssl=1","keywords":["#running","#sports","france","grenoble","running","running routes","sports","travel"],"articleSection":["Europe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/","url":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/","name":"Where to run in Grenoble?\u00a0 Running back home! - Run n&#039; Roll","isPartOf":{"@id":"https:\/\/run-and-roll.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#primaryimage"},"image":{"@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg?fit=1920%2C1280&ssl=1","datePublished":"2023-02-18T12:54:40+00:00","dateModified":"2023-11-07T15:46:19+00:00","description":"Doing an exchange semester in the capital of the Alps? Pack your road and your trail running shoes, I'm taking you!","breadcrumb":{"@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#primaryimage","url":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg?fit=1920%2C1280&ssl=1","contentUrl":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg?fit=1920%2C1280&ssl=1","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/run-and-roll.com\/where-to-run-in-grenoble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/run-and-roll.com\/"},{"@type":"ListItem","position":2,"name":"Where to run in Grenoble?\u00a0 Running back home!"}]},{"@type":"WebSite","@id":"https:\/\/run-and-roll.com\/#website","url":"https:\/\/run-and-roll.com\/","name":"Run n&#039; Roll","description":"Le guide des coureur\u2e31se\u2e31s voyageur\u2e31se\u2e31s et expatri\u00e9\u2e31e\u2e31s","publisher":{"@id":"https:\/\/run-and-roll.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/run-and-roll.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/run-and-roll.com\/#organization","name":"Run n&#039; Roll","url":"https:\/\/run-and-roll.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/run-and-roll.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2022\/03\/cropped-cropped-cropped-cropped-cropped-RUN-N-roll-v6-2-1.png?fit=1500%2C844&ssl=1","contentUrl":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2022\/03\/cropped-cropped-cropped-cropped-cropped-RUN-N-roll-v6-2-1.png?fit=1500%2C844&ssl=1","width":1500,"height":844,"caption":"Run n&#039; Roll"},"image":{"@id":"https:\/\/run-and-roll.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/run-and-roll.com\/#\/schema\/person\/817a2ddf7491e0acff8886f2dc54a32e","name":"Running Mzungu","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9e41d98daf143a11ea956e9d65b9193f35dbe529bb31c5f98847d0b4cf98d551?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9e41d98daf143a11ea956e9d65b9193f35dbe529bb31c5f98847d0b4cf98d551?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e41d98daf143a11ea956e9d65b9193f35dbe529bb31c5f98847d0b4cf98d551?s=96&d=mm&r=g","caption":"Running Mzungu"},"url":"https:\/\/run-and-roll.com\/fr\/author\/lisa-reboud\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/run-and-roll.com\/wp-content\/uploads\/2023\/02\/feature-photo.jpg?fit=1920%2C1280&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/posts\/427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/comments?post=427"}],"version-history":[{"count":0,"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/posts\/427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/media?parent=427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/categories?post=427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/run-and-roll.com\/fr\/wp-json\/wp\/v2\/tags?post=427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}